{"id":25,"date":"2022-11-21T22:23:43","date_gmt":"2022-11-21T22:23:43","guid":{"rendered":"https:\/\/hosting.bluegrow.es\/servicios\/"},"modified":"2023-10-10T17:43:31","modified_gmt":"2023-10-10T16:43:31","slug":"servicios","status":"publish","type":"page","link":"https:\/\/de2a2.com\/fr\/servicios\/","title":{"rendered":"Servicios"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e01edc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e01edc3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5001d1df\" data-id=\"5001d1df\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a1e86e7 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"4a1e86e7\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-19d96df8\" data-id=\"19d96df8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446b0899 elementor-widget elementor-widget-heading\" data-id=\"446b0899\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00e9ances de Neurocoaching Strat\u00e9gique personnalis\u00e9es <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ef2399 elementor-widget elementor-widget-text-editor\" data-id=\"45ef2399\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre promesse est que vous atteigniez une connaissance de soi m\u00eame d'\u00e9tablir et de renforcer des liens solides au sein de votre entreprise, tout en sentant une plus grande s\u00e9curit\u00e9 et une plus grande efficacit\u00e9 personnelle rena\u00eetre en vous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e8d7a33 elementor-tablet-align-left elementor-mobile-align-justify elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3e8d7a33\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Am\u00e9liorez vos relations maintenant !<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5703d1bb\" data-id=\"5703d1bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf58d94 elementor-widget elementor-widget-image\" data-id=\"cf58d94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-511\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-192df16b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"192df16b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a4d7b9\" data-id=\"1a4d7b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11dec83 elementor-widget elementor-widget-heading\" data-id=\"11dec83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment cela fonctionne-t-il ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72ae4ad2 elementor-widget elementor-widget-text-editor\" data-id=\"72ae4ad2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous travaillerons en sessions, o\u00f9 nous aborderons les d\u00e9fis en toute confidentialit\u00e9, dans un espace s\u00fbr et de mani\u00e8re personnalis\u00e9e, en convenant des r\u00e9sultats et en \u00e9valuant les attentes.<\/p><p>Gr\u00e2ce \u00e0 un diagnostic, vous irez \u00e0 la racine de l'origine de ce d\u00e9fi auquel vous \u00eates confront\u00e9.<\/p><p>Nous continuerons \u00e0 d\u00e9faire les enchev\u00eatrements pour approfondir les d\u00e9couvertes, renforcer la connaissance de soi et changer la situation par des actions qui vous redonnent le contr\u00f4le.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e350af elementor-widget elementor-widget-spacer\" data-id=\"4e350af\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33ef5c90 elementor-widget elementor-widget-heading\" data-id=\"33ef5c90\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c0 quels r\u00e9sultats pouvez-vous vous attendre ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f5545f elementor-widget elementor-widget-text-editor\" data-id=\"54f5545f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au fur et \u00e0 mesure que vous progresserez dans les s\u00e9ances, vous commencerez \u00e0 ressentir les r\u00e9sultats avec l'auto-\u00e9coute, la connaissance de soi et viendront les \u00e9tonnements de la fa\u00e7on dont cela affecte vos relations \u00e0 la fois au sein de votre famille et de votre entreprise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79c8b894 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79c8b894\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a09b070\" data-id=\"1a09b070\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71165140 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"71165140\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59fb0074\" data-id=\"59fb0074\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79210b6e elementor-widget elementor-widget-image\" data-id=\"79210b6e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4.png\" class=\"attachment-full size-full wp-image-704\" alt=\"\" srcset=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4.png 1000w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4-300x300.png 300w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4-150x150.png 150w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4-768x768.png 768w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-4-12x12.png 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bdbe7c6 elementor-widget elementor-widget-image-box\" data-id=\"2bdbe7c6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"#\">Augmentez votre propre estime de soi et celle de votre entourage<\/a><\/h4><p class=\"elementor-image-box-description\">Comprendre vos interactions et les mod\u00e8les qui influencent la qualit\u00e9 de votre relation vous redonne du pouvoir et restaure l'estime de soi en \u00e9largissant votre propre bien-\u00eatre et autour de vous.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11651f1a\" data-id=\"11651f1a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49a2219e elementor-widget elementor-widget-image\" data-id=\"49a2219e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-5-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-705\" alt=\"\" srcset=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-5-150x150.webp 150w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-5.webp 1000w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-5-600.webp 600w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-5-300.webp 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705bb169 elementor-widget elementor-widget-image-box\" data-id=\"705bb169\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"#\">Gagner en clart\u00e9 pour la prise de d\u00e9cision<\/a><\/h4><p class=\"elementor-image-box-description\">En \u00e9claircissant et en gagnant en clart\u00e9, vous verrez votre vision  qui vous aidera a prendre les bonnes decisions de fa\u00e7on coh\u00e9rentes et authentique.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0fcb66 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"b0fcb66\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d80ea6b elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"5d80ea6b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f7a5587 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1f7a5587\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c9dfb50\" data-id=\"5c9dfb50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-178b7432 elementor-widget elementor-widget-image\" data-id=\"178b7432\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-6-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-706\" alt=\"\" srcset=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-6-150x150.webp 150w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-6.webp 1000w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-6-600.webp 600w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-6-300.webp 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349a2091 elementor-widget elementor-widget-image-box\" data-id=\"349a2091\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"#\">D\u00e9velopper des techniques de communication assertives et efficaces<\/a><\/h4><p class=\"elementor-image-box-description\">Avec l'\u00e9coute, vous comprenez et reconnaissez comment vous travaillez, de sorte que vous reprenez le contr\u00f4le de votre communication interne et avec les autres sans aucune distorsion et avec une clart\u00e9 totale.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5484f3bb\" data-id=\"5484f3bb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c3ff06f elementor-widget elementor-widget-image\" data-id=\"1c3ff06f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-7-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-707\" alt=\"\" srcset=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-7-150x150.webp 150w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-7.webp 1000w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-7-600.webp 600w, https:\/\/de2a2.com\/wp-content\/uploads\/2023\/09\/WebX-7-300.webp 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-783cc945 elementor-widget elementor-widget-image-box\" data-id=\"783cc945\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"#\">G\u00e9rez vos \u00e9motions et limitez vos probl\u00e8mes<\/a><\/h4><p class=\"elementor-image-box-description\">Apprenez \u00e0 comprendre les sentiments et \u00e0 reconna\u00eetre et g\u00e9rer les \u00e9motions sans vous ruiner individuellement ou vos relations.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b277293 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b277293\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38c9a521\" data-id=\"38c9a521\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-153fdd35 elementor-widget elementor-widget-spacer\" data-id=\"153fdd35\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58c4c500 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58c4c500\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-189f0ef\" data-id=\"189f0ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13b9db8b elementor-widget elementor-widget-heading\" data-id=\"13b9db8b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne vous inqui\u00e9tez pas, toutes vos pr\u00e9occupations seront r\u00e9solues<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23377e2a elementor-widget elementor-widget-toggle\" data-id=\"23377e2a\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5901\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5901\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Combien de temps dureront les s\u00e9ances ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5901\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5901\"><p><span style=\"font-weight: 400;\">Les s\u00e9ances seront hebdomadaires et dureront entre 45 et 60 minutes, pendant 10 semaines. <\/span><span style=\"font-weight: 400;\">ajust\u00e1ndose<\/span><span style=\"font-weight: 400;\"> al momento, <\/span><span style=\"font-weight: 400;\">durante 10 semanas<\/span><span style=\"font-weight: 400;\">.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5902\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5902\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les s\u00e9ances ont-elles lieu virtuellement ou en personne ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5902\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5902\"><p><span style=\"font-weight: 400;\">Selon l'endroit o\u00f9 vous vous trouvez, nous nous mettrons d'accord sur l'option la plus pratique pour vous et les r\u00e9sultats que vous recherchez. <\/span><span style=\"font-weight: 400;\">busc\u00e1is<\/span><span style=\"font-weight: 400;\">.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5903\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-5903\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devons-nous impliquer toutes les parties dans les s\u00e9ances afin de travailler sur nos relations ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5903\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-5903\"><p>Pas n\u00e9cessairement, cela d\u00e9pend du cas. Avec notre approche, nous nous concentrerons sur le travail individuel et personnalis\u00e9 pour aborder et reconna\u00eetre les mod\u00e8les et comportements cl\u00e9s qui influencent la relation.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac87689 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ac87689\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7125ce5b\" data-id=\"7125ce5b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-678c3062 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"678c3062\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Commencez d\u00e8s maintenant \u00e0 transformer vos relations <\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3302ffbe elementor-mobile-align-justify elementor-align-right elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"3302ffbe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.link\/67wvdb\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discuter?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos robustos dentro de vuestro negocio, a la vez que sint\u00e1is una mayor seguridad y eficiencia personal renacer en vuestro interior. \u00a1Mejorad ya vuestras relaciones! \u00bfC\u00f3mo funciona? Trabajaremos en sesiones, donde abordaremos los retos con total [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Servicios - Carmen Celis<\/title>\n<meta name=\"description\" content=\"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/de2a2.com\/fr\/servicios\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios - Carmen Celis\" \/>\n<meta property=\"og:description\" content=\"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/de2a2.com\/fr\/servicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Carmen Celis\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T16:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/de2a2.com\/servicios\/\",\"url\":\"https:\/\/de2a2.com\/servicios\/\",\"name\":\"Servicios - Carmen Celis\",\"isPartOf\":{\"@id\":\"https:\/\/de2a2.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/de2a2.com\/servicios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/de2a2.com\/servicios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg\",\"datePublished\":\"2022-11-21T22:23:43+00:00\",\"dateModified\":\"2023-10-10T16:43:31+00:00\",\"description\":\"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/de2a2.com\/servicios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/de2a2.com\/servicios\/#primaryimage\",\"url\":\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg\",\"contentUrl\":\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/de2a2.com\/#website\",\"url\":\"https:\/\/de2a2.com\/\",\"name\":\"Carmen Celis\",\"description\":\"Neurocoaching Familioempresarial\",\"publisher\":{\"@id\":\"https:\/\/de2a2.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/de2a2.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/de2a2.com\/#organization\",\"name\":\"Carmen Celis\",\"url\":\"https:\/\/de2a2.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/de2a2.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/07\/DE2A2-By-Carmen-Logo-Beta_Mesa-de-trabajo-1-e1695221399281.webp\",\"contentUrl\":\"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/07\/DE2A2-By-Carmen-Logo-Beta_Mesa-de-trabajo-1-e1695221399281.webp\",\"width\":1920,\"height\":1627,\"caption\":\"Carmen Celis\"},\"image\":{\"@id\":\"https:\/\/de2a2.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios - Carmen Celis","description":"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/de2a2.com\/fr\/servicios\/","og_locale":"fr_FR","og_type":"article","og_title":"Servicios - Carmen Celis","og_description":"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos","og_url":"https:\/\/de2a2.com\/fr\/servicios\/","og_site_name":"Carmen Celis","article_modified_time":"2023-10-10T16:43:31+00:00","og_image":[{"url":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/de2a2.com\/servicios\/","url":"https:\/\/de2a2.com\/servicios\/","name":"Servicios - Carmen Celis","isPartOf":{"@id":"https:\/\/de2a2.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/de2a2.com\/servicios\/#primaryimage"},"image":{"@id":"https:\/\/de2a2.com\/servicios\/#primaryimage"},"thumbnailUrl":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg","datePublished":"2022-11-21T22:23:43+00:00","dateModified":"2023-10-10T16:43:31+00:00","description":"Sesiones personalizadas de Neurocoaching Estrat\u00e9gico Nuestra promesa es que logr\u00e9is un autoconocimiento de uno mism@ para establecer y fortalecer v\u00ednculos","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/de2a2.com\/servicios\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/de2a2.com\/servicios\/#primaryimage","url":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg","contentUrl":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/08\/Sentada-al-reves-Interior-1024x683.jpg"},{"@type":"WebSite","@id":"https:\/\/de2a2.com\/#website","url":"https:\/\/de2a2.com\/","name":"Carmen Celis","description":"Neurocoaching Familioempresarial","publisher":{"@id":"https:\/\/de2a2.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/de2a2.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/de2a2.com\/#organization","name":"Carmen Celis","url":"https:\/\/de2a2.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/de2a2.com\/#\/schema\/logo\/image\/","url":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/07\/DE2A2-By-Carmen-Logo-Beta_Mesa-de-trabajo-1-e1695221399281.webp","contentUrl":"https:\/\/de2a2.com\/wp-content\/uploads\/2023\/07\/DE2A2-By-Carmen-Logo-Beta_Mesa-de-trabajo-1-e1695221399281.webp","width":1920,"height":1627,"caption":"Carmen Celis"},"image":{"@id":"https:\/\/de2a2.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":66,"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":904,"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/pages\/25\/revisions\/904"}],"wp:attachment":[{"href":"https:\/\/de2a2.com\/fr\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}